{"id":88498,"date":"2025-07-15T17:01:53","date_gmt":"2025-07-15T22:01:53","guid":{"rendered":"https:\/\/www.ucaldas.edu.co\/portal\/?p=88498"},"modified":"2025-07-24T10:49:38","modified_gmt":"2025-07-24T15:49:38","slug":"universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro","status":"publish","type":"post","link":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\/","title":{"rendered":"Universidad de Caldas fortalece alianzas para llevar el programa de Medicina al Magdalena Centro"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-88504 size-full\" src=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-15-at-1.04.22-PM-scaled-e1752616798514.jpeg\" alt=\"Visita a La Dorada\" width=\"900\" height=\"474\" \/><\/p>\n<p style=\"text-align: justify;\">Como parte de su compromiso con el fortalecimiento del sector salud y la ampliaci\u00f3n de su oferta acad\u00e9mica, la Universidad de Caldas sostuvo un significativo encuentro con gerentes de hospitales del Magdalena Centro, una regi\u00f3n que abarca departamentos como Caldas, Tolima, Cundinamarca, Boyac\u00e1, Antioquia y Santander. Durante la reuni\u00f3n, se socializ\u00f3 el proyecto para implementar el programa de Medicina en la sede Guarin\u00f3, con miras a establecer convenios docentes-asistenciales que permitan a los estudiantes realizar sus pr\u00e1cticas en instituciones de salud del territorio.<!--more--><\/p>\n<p style=\"text-align: justify;\">El gobernador de Caldas reiter\u00f3 su compromiso con la iniciativa, anunciando una inversi\u00f3n inicial cercana a los 250 millones de pesos para la adquisici\u00f3n de mesas especiales de medicina. Adem\u00e1s, el Ministerio de Salud, representado por el asesor de despacho Wilmar Hernando G\u00f3mez, expres\u00f3 su inter\u00e9s en apoyar el proyecto, revisando la viabilidad de construir un centro de salud en la Ciudadela Universitaria y estudiando formas de vinculaci\u00f3n institucional a la propuesta. \u201cEsta apuesta responde a la pol\u00edtica nacional de democratizaci\u00f3n del acceso a la carrera de Medicina. Queremos que j\u00f3venes de territorios hist\u00f3ricamente afectados por el conflicto, como el Magdalena Centro, accedan a una formaci\u00f3n de calidad sin necesidad de migrar a las capitales\u201d, afirm\u00f3 Wilmar G\u00f3mez.<\/p>\n<p style=\"text-align: justify;\">Por su parte, el rector Fabio Hernando Arias Orozco enfatiz\u00f3 que este proyecto integra a municipios de seis departamentos en una propuesta educativa incluyente y descentralizada. \u201cEstamos pensando en iniciar inscripciones en agosto del pr\u00f3ximo a\u00f1o, mientras avanzamos en el registro calificado. El objetivo es que este programa sea una realidad para el primer semestre de 2027. Ya iniciamos la construcci\u00f3n de 10 casas para residencia estudiantil y se fortalecer\u00e1 la ruta del conocimiento para el transporte de los estudiantes\u201d, explic\u00f3.<\/p>\n<p style=\"text-align: justify;\">La directora del Programa de Medicina, Luz Helena Sep\u00falveda Gallego, manifest\u00f3 su entusiasmo frente a la acogida del proyecto por parte de los hospitales, resaltando la importancia de los convenios asistenciales como pilar fundamental para la formaci\u00f3n m\u00e9dica. \u201cEs un proyecto con un alt\u00edsimo impacto en la regi\u00f3n. Vamos a iniciar un censo de profesionales de la salud que puedan ser docentes en la zona, lo cual permitir\u00e1 consolidar una propuesta educativa con enfoque territorial\u201d, indic\u00f3.<\/p>\n<p style=\"text-align: justify;\">El encuentro fue tambi\u00e9n un espacio para reafirmar la articulaci\u00f3n entre universidad, Gobierno Departamental, Ministerio de Salud y actores del sector salud, como herramienta para cerrar brechas de acceso a la educaci\u00f3n y atenci\u00f3n m\u00e9dica en comunidades rurales y vulnerables. La Universidad de Caldas avanza as\u00ed en su prop\u00f3sito de consolidar una sede especializada en medicina, enfermer\u00eda, producci\u00f3n agropecuaria y agro tecnolog\u00eda en Guarin\u00f3.<\/p>\n<p style=\"text-align: justify;\">Finalmente, los directores y gerentes hospitalarios coincidieron en la importancia de trabajar en equipo para que la regi\u00f3n cuente con profesionales formados desde y para el Magdalena Centro. Este hito acad\u00e9mico y social se perfila como un motor de transformaci\u00f3n regional, apost\u00e1ndole a la educaci\u00f3n, la salud y el desarrollo con equidad territorial.<\/p>\n<p style=\"text-align: justify;\"><strong>Anexos:<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Rector-Universidad-de-Caldas-Fabio-Hernando-Arias-Orozco.mp3\"><strong>-Audio Rector Universidad de Caldas &#8211; Fabio Hernando Arias Orozco<\/strong><\/a><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-88498-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Rector-Universidad-de-Caldas-Fabio-Hernando-Arias-Orozco.mp3?_=1\" \/><a href=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Rector-Universidad-de-Caldas-Fabio-Hernando-Arias-Orozco.mp3\">https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Rector-Universidad-de-Caldas-Fabio-Hernando-Arias-Orozco.mp3<\/a><\/audio>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Gobernador-de-Caldas-Henry-Gutierrez.mp3\"><strong>-Audio Gobernador de Caldas &#8211; Henry Guti\u00e9rrez \u00c1ngel<\/strong><\/a><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-88498-2\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Gobernador-de-Caldas-Henry-Gutierrez.mp3?_=2\" \/><a href=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Gobernador-de-Caldas-Henry-Gutierrez.mp3\">https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Gobernador-de-Caldas-Henry-Gutierrez.mp3<\/a><\/audio>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Directora-del-Programa-de-Medicina-de-la-Universidad-de-Caldas-Luz-Helena-Sepulveda-Gallego.mp3\"><strong>-Audio Directora del Programa de Medicina de la Universidad de Caldas &#8211; Luz Helena Sep\u00falveda Gallego.<\/strong><\/a><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-88498-3\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Directora-del-Programa-de-Medicina-de-la-Universidad-de-Caldas-Luz-Helena-Sepulveda-Gallego.mp3?_=3\" \/><a href=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Directora-del-Programa-de-Medicina-de-la-Universidad-de-Caldas-Luz-Helena-Sepulveda-Gallego.mp3\">https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Directora-del-Programa-de-Medicina-de-la-Universidad-de-Caldas-Luz-Helena-Sepulveda-Gallego.mp3<\/a><\/audio>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Audio-Gerente-Hospital-San-Vicente-de-Paul-Fresno-Tolima-Diana-Maria-Tabares.mp3\"><strong>-Audio Gerente Hospital San Vicente de Pa\u00fal, Fresno Tolima &#8211; Diana Mar\u00eda Tabares.<\/strong><\/a><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-88498-4\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Audio-Gerente-Hospital-San-Vicente-de-Paul-Fresno-Tolima-Diana-Maria-Tabares.mp3?_=4\" \/><a href=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Audio-Gerente-Hospital-San-Vicente-de-Paul-Fresno-Tolima-Diana-Maria-Tabares.mp3\">https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Audio-Gerente-Hospital-San-Vicente-de-Paul-Fresno-Tolima-Diana-Maria-Tabares.mp3<\/a><\/audio>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Audio-Gerente-Hospital-San-Jose-Samana-Stephanie-Lizeth-Ortiz-Claros.mp3\"><strong>-Audio Audio Gerente, Hospital San, Jos\u00e9 Saman\u00e1 &#8211; Stephanie Lizeth Ortiz Claros.<\/strong><\/a><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-88498-5\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Audio-Gerente-Hospital-San-Jose-Samana-Stephanie-Lizeth-Ortiz-Claros.mp3?_=5\" \/><a href=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Audio-Gerente-Hospital-San-Jose-Samana-Stephanie-Lizeth-Ortiz-Claros.mp3\">https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/Audio-Gerente-Hospital-San-Jose-Samana-Stephanie-Lizeth-Ortiz-Claros.mp3<\/a><\/audio>\n<p>[\/vc_column_text][vc_images_carousel images=\u00bb88571,88572,88573,88574,88575,88576,88577,88578,88579,88580,88581,88582,88583,88584&#8243; img_size=\u00bb700&#215;500&#8243; autoplay=\u00bbyes\u00bb css=\u00bb\u00bb title=\u00bbGaler\u00eda de im\u00e1genes\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Como parte de su compromiso con el fortalecimiento del sector salud y la ampliaci\u00f3n de su oferta acad\u00e9mica, la Universidad de Caldas sostuvo un significativo encuentro con gerentes de hospitales del Magdalena Centro, una regi\u00f3n que abarca departamentos como Caldas, Tolima, Cundinamarca, Boyac\u00e1, Antioquia y Santander. Durante la reuni\u00f3n, se socializ\u00f3 el proyecto para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":88504,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,53,600,9799],"tags":[123,7542],"class_list":["post-88498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-universidad-al-dia","category-ucaldas-regional","category-destacados","tag-sede-la-dorada","tag-programa-medicina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Universidad de Caldas fortalece alianzas para llevar el programa de Medicina al Magdalena Centro .<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\\\/\"},\"author\":{\"name\":\"ofiprensa\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/person\\\/a1b482e23449158b4bc319926c074fdf\"},\"headline\":\"Universidad de Caldas fortalece alianzas para llevar el programa de Medicina al Magdalena Centro\",\"datePublished\":\"2025-07-15T22:01:53+00:00\",\"dateModified\":\"2025-07-24T15:49:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\\\/\"},\"wordCount\":684,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/WhatsApp-Image-2025-07-15-at-1.04.22-PM-scaled-e1752616798514.jpeg\",\"keywords\":[\"Sede La Dorada\",\"programa medicina\"],\"articleSection\":[\"Actualidad\",\"Universidad al D\u00eda\",\"UCaldas Regional\",\"Destacados\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\\\/\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\\\/\",\"name\":\"Universidad de Caldas fortalece alianzas para llevar el programa de Medicina al Magdalena Centro .\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/WhatsApp-Image-2025-07-15-at-1.04.22-PM-scaled-e1752616798514.jpeg\",\"datePublished\":\"2025-07-15T22:01:53+00:00\",\"dateModified\":\"2025-07-24T15:49:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/WhatsApp-Image-2025-07-15-at-1.04.22-PM-scaled-e1752616798514.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/WhatsApp-Image-2025-07-15-at-1.04.22-PM-scaled-e1752616798514.jpeg\",\"width\":900,\"height\":474,\"caption\":\"Visita a La Dorada\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Universidad de Caldas fortalece alianzas para llevar el programa de Medicina al Magdalena Centro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\",\"name\":\"Universidad de Caldas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\"},\"alternateName\":\"U. de Caldas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\",\"name\":\"Universidad de Caldas\",\"alternateName\":\"U. de Caldas\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Logo_horizontal_oscuroU-2023.png\",\"contentUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Logo_horizontal_oscuroU-2023.png\",\"width\":263,\"height\":101,\"caption\":\"Universidad de Caldas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/udecaldas\",\"https:\\\/\\\/x.com\\\/udecaldas\",\"https:\\\/\\\/www.youtube.com\\\/universidadcaldas\",\"https:\\\/\\\/www.instagram.com\\\/udecaldas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/person\\\/a1b482e23449158b4bc319926c074fdf\",\"name\":\"ofiprensa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411\",\"contentUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411\",\"caption\":\"ofiprensa\"},\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/author\\\/ofiprensa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Universidad de Caldas fortalece alianzas para llevar el programa de Medicina al Magdalena Centro .","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\/#article","isPartOf":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\/"},"author":{"name":"ofiprensa","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/person\/a1b482e23449158b4bc319926c074fdf"},"headline":"Universidad de Caldas fortalece alianzas para llevar el programa de Medicina al Magdalena Centro","datePublished":"2025-07-15T22:01:53+00:00","dateModified":"2025-07-24T15:49:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\/"},"wordCount":684,"publisher":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-15-at-1.04.22-PM-scaled-e1752616798514.jpeg","keywords":["Sede La Dorada","programa medicina"],"articleSection":["Actualidad","Universidad al D\u00eda","UCaldas Regional","Destacados"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\/","url":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\/","name":"Universidad de Caldas fortalece alianzas para llevar el programa de Medicina al Magdalena Centro .","isPartOf":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\/#primaryimage"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-15-at-1.04.22-PM-scaled-e1752616798514.jpeg","datePublished":"2025-07-15T22:01:53+00:00","dateModified":"2025-07-24T15:49:38+00:00","breadcrumb":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\/#primaryimage","url":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-15-at-1.04.22-PM-scaled-e1752616798514.jpeg","contentUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-15-at-1.04.22-PM-scaled-e1752616798514.jpeg","width":900,"height":474,"caption":"Visita a La Dorada"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-fortalece-alianzas-para-llevar-el-programa-de-medicina-al-magdalena-centro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ucaldas.edu.co\/portal\/"},{"@type":"ListItem","position":2,"name":"Universidad de Caldas fortalece alianzas para llevar el programa de Medicina al Magdalena Centro"}]},{"@type":"WebSite","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#website","url":"https:\/\/www.ucaldas.edu.co\/portal\/","name":"Universidad de Caldas","description":"","publisher":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization"},"alternateName":"U. de Caldas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ucaldas.edu.co\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization","name":"Universidad de Caldas","alternateName":"U. de Caldas","url":"https:\/\/www.ucaldas.edu.co\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2023\/11\/Logo_horizontal_oscuroU-2023.png","contentUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2023\/11\/Logo_horizontal_oscuroU-2023.png","width":263,"height":101,"caption":"Universidad de Caldas"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/udecaldas","https:\/\/x.com\/udecaldas","https:\/\/www.youtube.com\/universidadcaldas","https:\/\/www.instagram.com\/udecaldas\/"]},{"@type":"Person","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/person\/a1b482e23449158b4bc319926c074fdf","name":"ofiprensa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411","url":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411","contentUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411","caption":"ofiprensa"},"url":"https:\/\/www.ucaldas.edu.co\/portal\/author\/ofiprensa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts\/88498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/comments?post=88498"}],"version-history":[{"count":0,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts\/88498\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/media\/88504"}],"wp:attachment":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/media?parent=88498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/categories?post=88498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/tags?post=88498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}