{"id":43601,"date":"2018-10-11T22:01:06","date_gmt":"2018-10-11T22:01:06","guid":{"rendered":"https:\/\/www.ucaldas.edu.co\/portal\/?p=43601"},"modified":"2018-10-11T22:01:06","modified_gmt":"2018-10-11T22:01:06","slug":"egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia","status":"publish","type":"post","link":"https:\/\/www.ucaldas.edu.co\/portal\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\/","title":{"rendered":"Egresada de la U. de Caldas destaca su trabajo de grado en el \u201cProyecto Tesis\u201d: los trabajos m\u00e1s interesantes de Colombia"},"content":{"rendered":"<p style=\"text-align: center;\">SE TRATA DE ANG\u00c9LICA RODR\u00cdGUEZ GRAJALES<\/p>\n<p style=\"text-align: center;\"><strong>Egresada de la U. de Caldas destaca su trabajo de grado en el \u201cProyecto Tesis\u201d: <em>los trabajos m\u00e1s interesantes de Colombia<\/em><\/strong><\/p>\n<p style=\"text-align: right;\">11\/10\/2018<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43603 aligncenter\" src=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2018-10-11-at-4.27.27-PM.jpeg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2018-10-11-at-4.27.27-PM.jpeg 700w, https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2018-10-11-at-4.27.27-PM-300x171.jpeg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/>Ang\u00e9lica Rodr\u00edguez Grajales egresada del Programa de Artes pl\u00e1sticas de la Universidad de Caldas, participa en la d\u00e9cimo quinta versi\u00f3n del \u201cProyecto Tesis\u201d, una iniciativa que da continuidad al espacio de encuentro, confrontaci\u00f3n y divulgaci\u00f3n de los mejores trabajos de grado en Colombia.<\/p>\n<p><!--more--><\/p>\n<p>En esta oportunidad la artista pl\u00e1stica, participa con su proyecto <strong><em>L\u00edneas de tiempo<\/em><\/strong> el cual tuvo como objetivo comprender los objetos en los que prevalece la identidad y la memoria, \u201ces un ejercicio escult\u00f3rico de hilos que estructuran la red que teje el pasado y presente haciendo tangible el recorrido y la manera de habitar que se vive junto a estos objetos\u201d coment\u00f3 Rodr\u00edguez.<\/p>\n<p>&nbsp;<\/p>\n<p>Asimismo destac\u00f3 la importancia de participar en estos espacios que le permiten a los artistas continuar desarrollando nuevos proyectos, \u201cMi inspiraci\u00f3n surgi\u00f3 a partir de los objetos que podemos encontrar en la galer\u00eda de Manizales y est\u00e1 es una oportunidad muy importante porque puedo exponer mi trabajo fuera de la ciudad y darlo a conocer a otros artistas emergentes\u201d.<\/p>\n<p>El <strong><em>Proyecto Tesis<\/em><\/strong> tiene lugar en El Museo de Arte Contempor\u00e1neo de Bogot\u00e1 (MAC)\u00a0donde los asistentes pueden disfrutar de obras realizadas por artistas pl\u00e1sticos, visuales, dise\u00f1adores gr\u00e1ficos y de modas de las universidades m\u00e1s importantes del pa\u00eds en el campo de las artes.<\/p>\n<p><strong>Informes: <\/strong>Oficina de Comunicaciones y Prensa Universidad de Caldas. Tel\u00e9fono: 8781500. Extensi\u00f3n: 12167<\/p>\n<p><strong>Redacci\u00f3n: <\/strong>Daniela S\u00e1nchez R\u00edos<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SE TRATA DE ANG\u00c9LICA RODR\u00cdGUEZ GRAJALES Egresada de la U. de Caldas destaca su trabajo de grado en el \u201cProyecto Tesis\u201d: los trabajos m\u00e1s interesantes de Colombia 11\/10\/2018 Ang\u00e9lica Rodr\u00edguez Grajales egresada del Programa de Artes pl\u00e1sticas de la Universidad de Caldas, participa en la d\u00e9cimo quinta versi\u00f3n del \u201cProyecto Tesis\u201d, una iniciativa que da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":43603,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,53,624],"tags":[3054,3055,3056,3057,3058],"class_list":["post-43601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-universidad-al-dia","category-ucaldas-activa","tag-egresada","tag-proyecto-tesis","tag-hilos","tag-artista-plastica","tag-trabajo-de-grado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Egresada de la U. de Caldas destaca su trabajo de grado en el \u201cProyecto Tesis\u201d: los trabajos m\u00e1s interesantes de Colombia .<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ucaldas.edu.co\/portal\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\\\/\"},\"author\":{\"name\":\"ofiprensa\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/person\\\/a1b482e23449158b4bc319926c074fdf\"},\"headline\":\"Egresada de la U. de Caldas destaca su trabajo de grado en el \u201cProyecto Tesis\u201d: los trabajos m\u00e1s interesantes de Colombia\",\"datePublished\":\"2018-10-11T22:01:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\\\/\"},\"wordCount\":303,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/WhatsApp-Image-2018-10-11-at-4.27.27-PM.jpeg\",\"keywords\":[\"egresada\",\"proyecto tesis\",\"hilos\",\"artista pl\u00e1stica\",\"trabajo de grado\"],\"articleSection\":[\"Actualidad\",\"Universidad al D\u00eda\",\"UCaldas Activa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\\\/\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\\\/\",\"name\":\"Egresada de la U. de Caldas destaca su trabajo de grado en el \u201cProyecto Tesis\u201d: los trabajos m\u00e1s interesantes de Colombia .\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/WhatsApp-Image-2018-10-11-at-4.27.27-PM.jpeg\",\"datePublished\":\"2018-10-11T22:01:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/WhatsApp-Image-2018-10-11-at-4.27.27-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/WhatsApp-Image-2018-10-11-at-4.27.27-PM.jpeg\",\"width\":700,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Egresada de la U. de Caldas destaca su trabajo de grado en el \u201cProyecto Tesis\u201d: los trabajos m\u00e1s interesantes de Colombia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\",\"name\":\"Universidad de Caldas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\"},\"alternateName\":\"U. de Caldas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\",\"name\":\"Universidad de Caldas\",\"alternateName\":\"U. de Caldas\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Logo_horizontal_oscuroU-2023.png\",\"contentUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Logo_horizontal_oscuroU-2023.png\",\"width\":263,\"height\":101,\"caption\":\"Universidad de Caldas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/udecaldas\",\"https:\\\/\\\/x.com\\\/udecaldas\",\"https:\\\/\\\/www.youtube.com\\\/universidadcaldas\",\"https:\\\/\\\/www.instagram.com\\\/udecaldas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/person\\\/a1b482e23449158b4bc319926c074fdf\",\"name\":\"ofiprensa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411\",\"contentUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411\",\"caption\":\"ofiprensa\"},\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/author\\\/ofiprensa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Egresada de la U. de Caldas destaca su trabajo de grado en el \u201cProyecto Tesis\u201d: los trabajos m\u00e1s interesantes de Colombia .","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ucaldas.edu.co\/portal\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ucaldas.edu.co\/portal\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\/#article","isPartOf":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\/"},"author":{"name":"ofiprensa","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/person\/a1b482e23449158b4bc319926c074fdf"},"headline":"Egresada de la U. de Caldas destaca su trabajo de grado en el \u201cProyecto Tesis\u201d: los trabajos m\u00e1s interesantes de Colombia","datePublished":"2018-10-11T22:01:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\/"},"wordCount":303,"publisher":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2018-10-11-at-4.27.27-PM.jpeg","keywords":["egresada","proyecto tesis","hilos","artista pl\u00e1stica","trabajo de grado"],"articleSection":["Actualidad","Universidad al D\u00eda","UCaldas Activa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ucaldas.edu.co\/portal\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\/","url":"https:\/\/www.ucaldas.edu.co\/portal\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\/","name":"Egresada de la U. de Caldas destaca su trabajo de grado en el \u201cProyecto Tesis\u201d: los trabajos m\u00e1s interesantes de Colombia .","isPartOf":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\/#primaryimage"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2018-10-11-at-4.27.27-PM.jpeg","datePublished":"2018-10-11T22:01:06+00:00","breadcrumb":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ucaldas.edu.co\/portal\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\/#primaryimage","url":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2018-10-11-at-4.27.27-PM.jpeg","contentUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2018-10-11-at-4.27.27-PM.jpeg","width":700,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.ucaldas.edu.co\/portal\/egresada-de-la-u-de-caldas-destaca-su-trabajo-de-grado-en-el-proyecto-tesis-los-trabajos-mas-interesantes-de-colombia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ucaldas.edu.co\/portal\/"},{"@type":"ListItem","position":2,"name":"Egresada de la U. de Caldas destaca su trabajo de grado en el \u201cProyecto Tesis\u201d: los trabajos m\u00e1s interesantes de Colombia"}]},{"@type":"WebSite","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#website","url":"https:\/\/www.ucaldas.edu.co\/portal\/","name":"Universidad de Caldas","description":"","publisher":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization"},"alternateName":"U. de Caldas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ucaldas.edu.co\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization","name":"Universidad de Caldas","alternateName":"U. de Caldas","url":"https:\/\/www.ucaldas.edu.co\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2023\/11\/Logo_horizontal_oscuroU-2023.png","contentUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2023\/11\/Logo_horizontal_oscuroU-2023.png","width":263,"height":101,"caption":"Universidad de Caldas"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/udecaldas","https:\/\/x.com\/udecaldas","https:\/\/www.youtube.com\/universidadcaldas","https:\/\/www.instagram.com\/udecaldas\/"]},{"@type":"Person","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/person\/a1b482e23449158b4bc319926c074fdf","name":"ofiprensa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411","url":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411","contentUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411","caption":"ofiprensa"},"url":"https:\/\/www.ucaldas.edu.co\/portal\/author\/ofiprensa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts\/43601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/comments?post=43601"}],"version-history":[{"count":0,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts\/43601\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/media\/43603"}],"wp:attachment":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/media?parent=43601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/categories?post=43601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/tags?post=43601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}