{"id":43411,"date":"2018-10-04T22:36:43","date_gmt":"2018-10-04T22:36:43","guid":{"rendered":"https:\/\/www.ucaldas.edu.co\/portal\/?p=43411"},"modified":"2018-10-04T22:36:43","modified_gmt":"2018-10-04T22:36:43","slug":"universidad-de-caldas-se-une-a-la-alimentaton-2018","status":"publish","type":"post","link":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-se-une-a-la-alimentaton-2018\/","title":{"rendered":"Universidad de Caldas se une a la \u201cAlimentat\u00f3n 2018\u201d"},"content":{"rendered":"<p style=\"text-align: center;\">CAMPA\u00d1A DEL BANCO DE ALIMENTOS ARQUIDIOCESANO DE ALIMENTOS<\/p>\n<p style=\"text-align: center;\"><strong>Universidad de Caldas se une a la \u201cAlimentat\u00f3n 2018\u201d<\/strong><\/p>\n<p style=\"text-align: right;\">5\/10\/2018<\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43412 aligncenter\" src=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/10\/alimenta-compressor.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/10\/alimenta-compressor.jpg 700w, https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/10\/alimenta-compressor-300x171.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/>La Universidad de Caldas a trav\u00e9s de la Vicerrector\u00eda de Proyecci\u00f3n Universitaria, <\/strong>participar\u00e1 entre el 16 y el 23 de Octubre en la <strong>\u201cAlimentat\u00f3n\u201d<\/strong> una colecta nacional, que busca mejorar las condiciones nutricionales de la poblaci\u00f3n vulnerable en Colombia a trav\u00e9s de las donaciones que organizaciones o personas pueden hacer a los Bancos de Alimentos del pa\u00eds.<\/p>\n<p><!--more--><\/p>\n<p>La vinculaci\u00f3n de la instituci\u00f3n ser\u00e1 a trav\u00e9s de la instalaci\u00f3n de un punto de acopio de <strong>alimentos no perecederos<\/strong> en las diferentes sedes y para los <strong>Conciertos de Temporada de la Orquesta Sinf\u00f3nica de Caldas los d\u00edas 22 y 23 de octubre, <\/strong>\u00a0el ingreso del p\u00fablico ser\u00e1 a trav\u00e9s de donaci\u00f3n de alimentos de dif\u00edcil deterioro.<\/p>\n<p>&nbsp;<\/p>\n<p>La meta es recolectar 10mil kilos de productos no perecederos, los ciudadanos podr\u00e1n donar granos como \u00a0las lentejas, blanquillos, frijoles, garbanzos y arvejas, as\u00ed como pastas, sal, az\u00facar, panela, caf\u00e9, galletas, at\u00fan, sardinas, aceite, chocolate, especias, entre otros.<\/p>\n<p>&nbsp;<\/p>\n<p>Los alimentos recolectados ser\u00e1n distribuidos en seis instituciones que atienden poblaci\u00f3n vulnerable de Manizales, tales como:\u00a0 \u00a0Hogar Nuestra Se\u00f1ora del Rosario, \u00a0Fundaci\u00f3n Cuerpo de Voluntarias Damas Rosadas,<\/p>\n<p>Fundaci\u00f3n Padres Rogacionistas, \u00a0Fundaci\u00f3n Fedevida, Mercados solidarios, del Banco Arquidiocesano de Alimentos de Manizales y la \u00a0Fundaci\u00f3n Sin Fronteras, que ayuda a los compatriotas venezolanos residentes en Manizales.<\/p>\n<p><strong>Informes: <\/strong>Oficina de Comunicaciones y Prensa Universidad de Caldas. Tel\u00e9fono: 8781500 Extensi\u00f3n: 12167<\/p>\n<p><strong>Redacci\u00f3n: <\/strong>Adriana Salazar Villegas<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CAMPA\u00d1A DEL BANCO DE ALIMENTOS ARQUIDIOCESANO DE ALIMENTOS Universidad de Caldas se une a la \u201cAlimentat\u00f3n 2018\u201d 5\/10\/2018 &nbsp; La Universidad de Caldas a trav\u00e9s de la Vicerrector\u00eda de Proyecci\u00f3n Universitaria, participar\u00e1 entre el 16 y el 23 de Octubre en la \u201cAlimentat\u00f3n\u201d una colecta nacional, que busca mejorar las condiciones nutricionales de la poblaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":43412,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[48,53,617],"tags":[74,725,2935,3038,3039],"class_list":["post-43411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-universidad-al-dia","category-ucaldas-colaborativa","tag-campana","tag-recoleccion","tag-osc","tag-solidaridad","tag-alimentaton"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Universidad de Caldas se une a la \u201cAlimentat\u00f3n 2018\u201d .<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-se-une-a-la-alimentaton-2018\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-se-une-a-la-alimentaton-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-se-une-a-la-alimentaton-2018\\\/\"},\"author\":{\"name\":\"ofiprensa\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/person\\\/a1b482e23449158b4bc319926c074fdf\"},\"headline\":\"Universidad de Caldas se une a la \u201cAlimentat\u00f3n 2018\u201d\",\"datePublished\":\"2018-10-04T22:36:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-se-une-a-la-alimentaton-2018\\\/\"},\"wordCount\":279,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-se-une-a-la-alimentaton-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/alimenta-compressor.jpg\",\"keywords\":[\"Campa\u00f1a\",\"recolecci\u00f3n\",\"OSC\",\"solidaridad\",\"alimentat\u00f3n\"],\"articleSection\":[\"Actualidad\",\"Universidad al D\u00eda\",\"UCaldas Colaborativa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-se-une-a-la-alimentaton-2018\\\/\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-se-une-a-la-alimentaton-2018\\\/\",\"name\":\"Universidad de Caldas se une a la \u201cAlimentat\u00f3n 2018\u201d .\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-se-une-a-la-alimentaton-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-se-une-a-la-alimentaton-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/alimenta-compressor.jpg\",\"datePublished\":\"2018-10-04T22:36:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-se-une-a-la-alimentaton-2018\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-se-une-a-la-alimentaton-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-se-une-a-la-alimentaton-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/alimenta-compressor.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/alimenta-compressor.jpg\",\"width\":700,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/universidad-de-caldas-se-une-a-la-alimentaton-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Universidad de Caldas se une a la \u201cAlimentat\u00f3n 2018\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\",\"name\":\"Universidad de Caldas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\"},\"alternateName\":\"U. de Caldas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\",\"name\":\"Universidad de Caldas\",\"alternateName\":\"U. de Caldas\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Logo_horizontal_oscuroU-2023.png\",\"contentUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Logo_horizontal_oscuroU-2023.png\",\"width\":263,\"height\":101,\"caption\":\"Universidad de Caldas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/udecaldas\",\"https:\\\/\\\/x.com\\\/udecaldas\",\"https:\\\/\\\/www.youtube.com\\\/universidadcaldas\",\"https:\\\/\\\/www.instagram.com\\\/udecaldas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/person\\\/a1b482e23449158b4bc319926c074fdf\",\"name\":\"ofiprensa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1787779368\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1787779368\",\"contentUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1787779368\",\"caption\":\"ofiprensa\"},\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/author\\\/ofiprensa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Universidad de Caldas se une a la \u201cAlimentat\u00f3n 2018\u201d .","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-se-une-a-la-alimentaton-2018\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-se-une-a-la-alimentaton-2018\/#article","isPartOf":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-se-une-a-la-alimentaton-2018\/"},"author":{"name":"ofiprensa","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/person\/a1b482e23449158b4bc319926c074fdf"},"headline":"Universidad de Caldas se une a la \u201cAlimentat\u00f3n 2018\u201d","datePublished":"2018-10-04T22:36:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-se-une-a-la-alimentaton-2018\/"},"wordCount":279,"publisher":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-se-une-a-la-alimentaton-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/10\/alimenta-compressor.jpg","keywords":["Campa\u00f1a","recolecci\u00f3n","OSC","solidaridad","alimentat\u00f3n"],"articleSection":["Actualidad","Universidad al D\u00eda","UCaldas Colaborativa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-se-une-a-la-alimentaton-2018\/","url":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-se-une-a-la-alimentaton-2018\/","name":"Universidad de Caldas se une a la \u201cAlimentat\u00f3n 2018\u201d .","isPartOf":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-se-une-a-la-alimentaton-2018\/#primaryimage"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-se-une-a-la-alimentaton-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/10\/alimenta-compressor.jpg","datePublished":"2018-10-04T22:36:43+00:00","breadcrumb":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-se-une-a-la-alimentaton-2018\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-se-une-a-la-alimentaton-2018\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-se-une-a-la-alimentaton-2018\/#primaryimage","url":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/10\/alimenta-compressor.jpg","contentUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/10\/alimenta-compressor.jpg","width":700,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.ucaldas.edu.co\/portal\/universidad-de-caldas-se-une-a-la-alimentaton-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ucaldas.edu.co\/portal\/"},{"@type":"ListItem","position":2,"name":"Universidad de Caldas se une a la \u201cAlimentat\u00f3n 2018\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#website","url":"https:\/\/www.ucaldas.edu.co\/portal\/","name":"Universidad de Caldas","description":"","publisher":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization"},"alternateName":"U. de Caldas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ucaldas.edu.co\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization","name":"Universidad de Caldas","alternateName":"U. de Caldas","url":"https:\/\/www.ucaldas.edu.co\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2023\/11\/Logo_horizontal_oscuroU-2023.png","contentUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2023\/11\/Logo_horizontal_oscuroU-2023.png","width":263,"height":101,"caption":"Universidad de Caldas"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/udecaldas","https:\/\/x.com\/udecaldas","https:\/\/www.youtube.com\/universidadcaldas","https:\/\/www.instagram.com\/udecaldas\/"]},{"@type":"Person","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/person\/a1b482e23449158b4bc319926c074fdf","name":"ofiprensa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1787779368","url":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1787779368","contentUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1787779368","caption":"ofiprensa"},"url":"https:\/\/www.ucaldas.edu.co\/portal\/author\/ofiprensa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts\/43411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/comments?post=43411"}],"version-history":[{"count":0,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts\/43411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/media\/43412"}],"wp:attachment":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/media?parent=43411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/categories?post=43411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/tags?post=43411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}