{"id":40258,"date":"2018-04-06T18:33:12","date_gmt":"2018-04-06T18:33:12","guid":{"rendered":"https:\/\/www.ucaldas.edu.co\/portal\/?p=40258"},"modified":"2018-04-12T21:11:17","modified_gmt":"2018-04-12T21:11:17","slug":"candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera","status":"publish","type":"post","link":"https:\/\/www.ucaldas.edu.co\/portal\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\/","title":{"rendered":"Candidatos a la #Rector\u00edaUCaldas2018 dialogaron sobre sostenibilidad financiera"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-40259 aligncenter\" src=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/04\/foro-compressor.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/04\/foro-compressor.jpg 700w, https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/04\/foro-compressor-300x171.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/strong><\/p>\n<p><strong>Sostenibilidad financiera fue el tema<\/strong> del <a href=\"https:\/\/www.ucaldas.edu.co\/portal\/participe-en-los-foros-tematicos-con-los-candidatos-a-la-rectoriaucaldas2018\/\"><strong>primero de los cuatros foros tem\u00e1ticos con los candidatos a la #Rector\u00edaUCaldas2018<\/strong> (ver programaci\u00f3n)<\/a>, que tuvo lugar este viernes 6 de abril del 2018. En \u00e9l <strong>participaron siete de los ochos aspirantes a la rector\u00eda <\/strong>de la Universidad de Caldas para el periodo 2018-2022: Andr\u00e9s Felipe Betancourth L\u00f3pez, Alejandro Ceballos M\u00e1rquez, Francisco Arturo Vallejo Garc\u00eda, Juan Carlos G\u00f3mez Montoya, Jos\u00e9 Jes\u00fas Ramos Giraldo, Gabriel Gallego Montes y Jos\u00e9 Alexander Rivadeneira Salgado.<\/p>\n<p><!--more--><\/p>\n<p>Germ\u00e1n Albeiro Casta\u00f1o Duque, <strong>Vicerrector de la U. Nacional de Colombia sede Manizales, fue el moderador del foro y destac\u00f3 que los candidatos a la #Rector\u00edaUCaldas2018 tienen muy buen conocimiento del tema financiero, <\/strong>que es muy complejo y de mucha gesti\u00f3n.<\/p>\n<p>\u201c<strong>Veo en ellos mucha motivaci\u00f3n con la sostenibilidad financiera. Las universidades p\u00fablicas en general tienen que hacer un esfuerzo de reunirse, convocarse y realizar planteamientos \u00fanicos<\/strong>, pero pensando al largo plazo y no buscando s\u00f3lo sus intereses, sino que la propuesta unificada que se ejecute desde el Sistema Universitario Estatal (SUE) beneficie en el largo plazo a todo el sistema\u201d, explic\u00f3.<\/p>\n<p><strong>Los candidatos responden<\/strong><\/p>\n<p>La U. de Caldas tiene un d\u00e9ficit en su funcionamiento cercano a los $12 mil millones. \u00bfQu\u00e9 lo motiva a ser rector de la Universidad con un d\u00e9ficit como este y cu\u00e1l o cu\u00e1les son las estrategias que usted desarrollar\u00e1 para subsanarlo, de tal manera que en dos a\u00f1os se vea claramente que se ha logrado disminuir ese d\u00e9ficit?<\/p>\n<p><strong>\u00a0Andr\u00e9s Felipe Betancourth L\u00f3pez<\/strong><\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-40261 size-thumbnail\" src=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/04\/IMG_4311-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/strong><\/p>\n<p>\u00abMi motivaci\u00f3n es mi v\u00ednculo con la U. de Caldas. Asumir la gesti\u00f3n de la Universidad tiene que ver con la convicci\u00f3n de que pese al d\u00e9ficit no creo que seamos una Instituci\u00f3n en crisis\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Alejandro Ceballos M\u00e1rquez<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-40263 size-thumbnail alignleft\" src=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/04\/IMG_4314-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/p>\n<p>\u00abLo que soy como persona y profesional se lo debo a la Instituci\u00f3n. Me duele la U. de Caldas porque vengo de sus entra\u00f1as. Me gustan los retos y cuando fui decano de Agropecuarias tambi\u00e9n asumimos retos financieros\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Francisco Arturo Vallejo Garc\u00eda<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-40264 size-thumbnail alignleft\" src=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/04\/IMG_4328-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/p>\n<p>\u00abLa Rector\u00eda me motiva porque he estado siempre en lo p\u00fablico. Me he dedicado a llevar la educaci\u00f3n p\u00fablica en el mismo nivel de la educaci\u00f3n privada. Los retos son la financiaci\u00f3n y la permanencia en el futuro\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Juan Carlos G\u00f3mez Montoya<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-40265 size-thumbnail alignleft\" src=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/04\/IMG_4338-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/p>\n<p>\u00abMi motivaci\u00f3n es como egresado de la U. de Caldas y quien hizo parte de consejos Superior y Acad\u00e9mico. Mi estrategia es llamar a la unidad interna y externa, fundamental para ayudarle a las universidades estatales\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Jos\u00e9 Jes\u00fas Ramos Giraldo<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-40266 size-thumbnail\" src=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/04\/IMG_4342-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/p>\n<p>\u00abHe estado en la U. de Caldas desde 1973, desde ah\u00ed no me he desligado de la Instituci\u00f3n. Me motiva el devolver esa gratitud con mi segunda casa. Este no es un barco hundido y no gracias al Gobierno Nacional\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Gabriel Gallego Montes<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-40267 size-thumbnail alignleft\" src=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/04\/IMG_4348-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/p>\n<p>\u00abMe motiva ser rector porque conozco la U desde adentro. Proponemos: actualizaci\u00f3n del estatuto financiero, apoyo a acciones del SUE, desarrollo de estampillas pro Universidad y gestiones ante MinHacienda\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Jos\u00e9 Alexander Rivadeneira Salgado<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-40268 size-thumbnail alignleft\" src=\"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/04\/IMG_4351-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/p>\n<p>\u00abCreo que tengo el criterio suficiente para liderar los procesos de la U. Para poder exigir responsabilidades estatales se tienen que cumplir con unos deberes. La U. no est\u00e1 en crisis, pero s\u00ed en riesgo\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.1759256397469551.1073745978.107054166023124&amp;type=1&amp;l=5ddb6b9de5\" target=\"_blank\" rel=\"noopener\">GALER\u00cdA: Conozca im\u00e1genes del primer foro tem\u00e1tico con los candidatos a la #Rector\u00edaUCaldas2018<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>VIDEO: Reviva la transmisi\u00f3n del primer foro tem\u00e1tico con los candidatos a la #Rector\u00edaUCaldas2018<\/strong><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/bS1ypxBWK1s\" width=\"860\" height=\"515\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Segundo foro<\/strong><\/p>\n<p>Participe en el segundo \u00a0foro tem\u00e1tico con los candidatos a la #Rector\u00edaUCaldas2018, que tendr\u00e1 como tema la Ciencia, tecnolog\u00eda e innovaci\u00f3n. La cita es el pr\u00f3ximo jueves 12 de abril del 2018 de 9:00 a.m. a 12:00 m. en la Sala Carlos N\u00e1der N\u00e1der, Campus Central U. de Caldas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Informes:<\/strong>\u00a0Oficina de Comunicaciones y Prensa U. de Caldas, tel\u00e9fono 878 15 00 extensi\u00f3n 12 167.<\/p>\n<p><strong>Redacci\u00f3n:<\/strong> Margarita Laverde<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sostenibilidad financiera fue el tema del primero de los cuatros foros tem\u00e1ticos con los candidatos a la #Rector\u00edaUCaldas2018 (ver programaci\u00f3n), que tuvo lugar este viernes 6 de abril del 2018. En \u00e9l participaron siete de los ochos aspirantes a la rector\u00eda de la Universidad de Caldas para el periodo 2018-2022: Andr\u00e9s Felipe Betancourth L\u00f3pez, Alejandro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":40259,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,53,620],"tags":[77,79,95,1183,1750,2449],"class_list":["post-40258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-universidad-al-dia","category-ucaldas-transparente","tag-administracion","tag-foro","tag-universidad-de-caldas","tag-rectoria","tag-candidatos","tag-sostenibilidad-financiera"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Candidatos a la #Rector\u00edaUCaldas2018 dialogaron sobre sostenibilidad financiera .<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ucaldas.edu.co\/portal\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\\\/\"},\"author\":{\"name\":\"ofiprensa\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/person\\\/a1b482e23449158b4bc319926c074fdf\"},\"headline\":\"Candidatos a la #Rector\u00edaUCaldas2018 dialogaron sobre sostenibilidad financiera\",\"datePublished\":\"2018-04-06T18:33:12+00:00\",\"dateModified\":\"2018-04-12T21:11:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\\\/\"},\"wordCount\":697,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/foro-compressor.jpg\",\"keywords\":[\"Administraci\u00f3n\",\"foro\",\"Universidad De Caldas\",\"Rector\u00eda\",\"candidatos\",\"sostenibilidad financiera\"],\"articleSection\":[\"Actualidad\",\"Universidad al D\u00eda\",\"UCaldas Transparente\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\\\/\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\\\/\",\"name\":\"Candidatos a la #Rector\u00edaUCaldas2018 dialogaron sobre sostenibilidad financiera .\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/foro-compressor.jpg\",\"datePublished\":\"2018-04-06T18:33:12+00:00\",\"dateModified\":\"2018-04-12T21:11:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/foro-compressor.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/foro-compressor.jpg\",\"width\":700,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidatos a la #Rector\u00edaUCaldas2018 dialogaron sobre sostenibilidad financiera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\",\"name\":\"Universidad de Caldas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\"},\"alternateName\":\"U. de Caldas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\",\"name\":\"Universidad de Caldas\",\"alternateName\":\"U. de Caldas\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Logo_horizontal_oscuroU-2023.png\",\"contentUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Logo_horizontal_oscuroU-2023.png\",\"width\":263,\"height\":101,\"caption\":\"Universidad de Caldas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/udecaldas\",\"https:\\\/\\\/x.com\\\/udecaldas\",\"https:\\\/\\\/www.youtube.com\\\/universidadcaldas\",\"https:\\\/\\\/www.instagram.com\\\/udecaldas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/person\\\/a1b482e23449158b4bc319926c074fdf\",\"name\":\"ofiprensa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1778707214\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1778707214\",\"contentUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1778707214\",\"caption\":\"ofiprensa\"},\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/author\\\/ofiprensa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Candidatos a la #Rector\u00edaUCaldas2018 dialogaron sobre sostenibilidad financiera .","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ucaldas.edu.co\/portal\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ucaldas.edu.co\/portal\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\/#article","isPartOf":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\/"},"author":{"name":"ofiprensa","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/person\/a1b482e23449158b4bc319926c074fdf"},"headline":"Candidatos a la #Rector\u00edaUCaldas2018 dialogaron sobre sostenibilidad financiera","datePublished":"2018-04-06T18:33:12+00:00","dateModified":"2018-04-12T21:11:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\/"},"wordCount":697,"publisher":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/04\/foro-compressor.jpg","keywords":["Administraci\u00f3n","foro","Universidad De Caldas","Rector\u00eda","candidatos","sostenibilidad financiera"],"articleSection":["Actualidad","Universidad al D\u00eda","UCaldas Transparente"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ucaldas.edu.co\/portal\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\/","url":"https:\/\/www.ucaldas.edu.co\/portal\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\/","name":"Candidatos a la #Rector\u00edaUCaldas2018 dialogaron sobre sostenibilidad financiera .","isPartOf":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\/#primaryimage"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/04\/foro-compressor.jpg","datePublished":"2018-04-06T18:33:12+00:00","dateModified":"2018-04-12T21:11:17+00:00","breadcrumb":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ucaldas.edu.co\/portal\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\/#primaryimage","url":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/04\/foro-compressor.jpg","contentUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2018\/04\/foro-compressor.jpg","width":700,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.ucaldas.edu.co\/portal\/candidatos-a-la-rectoriaucaldas2018-dialogaron-sobre-sostenibilidad-financiera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ucaldas.edu.co\/portal\/"},{"@type":"ListItem","position":2,"name":"Candidatos a la #Rector\u00edaUCaldas2018 dialogaron sobre sostenibilidad financiera"}]},{"@type":"WebSite","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#website","url":"https:\/\/www.ucaldas.edu.co\/portal\/","name":"Universidad de Caldas","description":"","publisher":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization"},"alternateName":"U. de Caldas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ucaldas.edu.co\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization","name":"Universidad de Caldas","alternateName":"U. de Caldas","url":"https:\/\/www.ucaldas.edu.co\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2023\/11\/Logo_horizontal_oscuroU-2023.png","contentUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2023\/11\/Logo_horizontal_oscuroU-2023.png","width":263,"height":101,"caption":"Universidad de Caldas"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/udecaldas","https:\/\/x.com\/udecaldas","https:\/\/www.youtube.com\/universidadcaldas","https:\/\/www.instagram.com\/udecaldas\/"]},{"@type":"Person","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/person\/a1b482e23449158b4bc319926c074fdf","name":"ofiprensa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1778707214","url":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1778707214","contentUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1778707214","caption":"ofiprensa"},"url":"https:\/\/www.ucaldas.edu.co\/portal\/author\/ofiprensa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts\/40258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/comments?post=40258"}],"version-history":[{"count":0,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts\/40258\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/media\/40259"}],"wp:attachment":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/media?parent=40258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/categories?post=40258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/tags?post=40258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}