{"id":35203,"date":"2017-04-26T15:19:38","date_gmt":"2017-04-26T20:19:38","guid":{"rendered":"https:\/\/www.ucaldas.edu.co\/portal\/?p=35203"},"modified":"2017-04-26T15:19:38","modified_gmt":"2017-04-26T20:19:38","slug":"estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2","status":"publish","type":"post","link":"https:\/\/www.ucaldas.edu.co\/portal\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\/","title":{"rendered":"Estudiantes, conozcan disposiciones para descuento electoral en los recibos de matr\u00edcula correspondientes al per\u00edodo 2017-2"},"content":{"rendered":"<p style=\"text-align: center;\">PLAZO M\u00c1XIMO PARA RECIBIR LAS COPIAS DE LOS CERTIFICADOS ELECTORALES SER\u00c1 EL 19 DE MAYO DEL 2017<\/p>\n<p style=\"text-align: center;\"><strong>Estudiantes, conozcan disposiciones para descuento electoral en los recibos de matr\u00edcula correspondientes al per\u00edodo 2017-2 \u00a0<\/strong><\/p>\n<p style=\"text-align: right;\">26\/04\/2017<\/p>\n<p><strong>\u00a0<img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.ucaldas.edu.co\/intranet2\/wp-content\/uploads\/2015\/11\/MOMENTOS-U-BICENTENAERIO-30-SEP-2014-20-300x200.jpg\" alt=\"MOMENTOS U BICENTENAERIO 30 SEP 2014 (20)\" \/><\/strong><\/p>\n<p>La <strong>Oficina de Admisiones y Registro Acad\u00e9mico<\/strong> de la Universidad de Caldas informa que con el fin de hacer la aplicaci\u00f3n del descuento electoral en los recibos de matr\u00edcula correspondientes al per\u00edodo 2017-2 se hace <strong>necesaria la recopilaci\u00f3n de los respectivos certificados electorales<\/strong> de los estudiantes que quieran y tengan derecho a este beneficio.<\/p>\n<p><!--more--><\/p>\n<p>Se recibir\u00e1n como v\u00e1lidos los certificaos del 25 de octubre del 2015 o el del Plebiscito del 2 de octubre del 2016. El <strong>plazo m\u00e1ximo para recibir las copias de los certificados electorales ser\u00e1 el 19 de mayo del 2017.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Adicionalmente, cada programa, deber\u00e1 enviar archivo en Excel de dicha relaci\u00f3n al correo <a href=\"mailto:liquidaciones.registro@ucaldas.edu.co\">liquidaciones.registro@ucaldas.edu.co<\/a>, con la siguiente informaci\u00f3n:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Nombre del Estudiante<\/li>\n<li>C\u00e9dula de ciudadan\u00eda<\/li>\n<li>C\u00f3digo estudiantil<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Informes: <\/strong>Oficina de Admisiones y Registro Acad\u00e9mico U. de Caldas, tel\u00e9fono 878 15 00 extensi\u00f3n 12 120.<\/p>\n<p><strong>Redacci\u00f3n:<\/strong> Margarita Laverde<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PLAZO M\u00c1XIMO PARA RECIBIR LAS COPIAS DE LOS CERTIFICADOS ELECTORALES SER\u00c1 EL 19 DE MAYO DEL 2017 Estudiantes, conozcan disposiciones para descuento electoral en los recibos de matr\u00edcula correspondientes al per\u00edodo 2017-2 \u00a0 26\/04\/2017 \u00a0 La Oficina de Admisiones y Registro Acad\u00e9mico de la Universidad de Caldas informa que con el fin de hacer la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[620,48,53],"tags":[730,731,77,408],"class_list":["post-35203","post","type-post","status-publish","format-standard","hentry","category-ucaldas-transparente","category-actualidad","category-universidad-al-dia","tag-certificado-electoral","tag-descuento","tag-administracion","tag-matricula"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudiantes, conozcan disposiciones para descuento electoral en los recibos de matr\u00edcula correspondientes al per\u00edodo 2017-2 .<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ucaldas.edu.co\/portal\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\\\/\"},\"author\":{\"name\":\"ofiprensa\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/person\\\/a1b482e23449158b4bc319926c074fdf\"},\"headline\":\"Estudiantes, conozcan disposiciones para descuento electoral en los recibos de matr\u00edcula correspondientes al per\u00edodo 2017-2\",\"datePublished\":\"2017-04-26T20:19:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\\\/\"},\"wordCount\":204,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.ucaldas.edu.co\\\/intranet2\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/MOMENTOS-U-BICENTENAERIO-30-SEP-2014-20-300x200.jpg\",\"keywords\":[\"certificado electoral\",\"descuento\",\"Administraci\u00f3n\",\"matr\u00edcula\"],\"articleSection\":[\"UCaldas Transparente\",\"Actualidad\",\"Universidad al D\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\\\/\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\\\/\",\"name\":\"Estudiantes, conozcan disposiciones para descuento electoral en los recibos de matr\u00edcula correspondientes al per\u00edodo 2017-2 .\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.ucaldas.edu.co\\\/intranet2\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/MOMENTOS-U-BICENTENAERIO-30-SEP-2014-20-300x200.jpg\",\"datePublished\":\"2017-04-26T20:19:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.ucaldas.edu.co\\\/intranet2\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/MOMENTOS-U-BICENTENAERIO-30-SEP-2014-20-300x200.jpg\",\"contentUrl\":\"http:\\\/\\\/www.ucaldas.edu.co\\\/intranet2\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/MOMENTOS-U-BICENTENAERIO-30-SEP-2014-20-300x200.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudiantes, conozcan disposiciones para descuento electoral en los recibos de matr\u00edcula correspondientes al per\u00edodo 2017-2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\",\"name\":\"Universidad de Caldas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\"},\"alternateName\":\"U. de Caldas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\",\"name\":\"Universidad de Caldas\",\"alternateName\":\"U. de Caldas\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Logo_horizontal_oscuroU-2023.png\",\"contentUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Logo_horizontal_oscuroU-2023.png\",\"width\":263,\"height\":101,\"caption\":\"Universidad de Caldas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/udecaldas\",\"https:\\\/\\\/x.com\\\/udecaldas\",\"https:\\\/\\\/www.youtube.com\\\/universidadcaldas\",\"https:\\\/\\\/www.instagram.com\\\/udecaldas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/person\\\/a1b482e23449158b4bc319926c074fdf\",\"name\":\"ofiprensa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411\",\"contentUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411\",\"caption\":\"ofiprensa\"},\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/author\\\/ofiprensa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudiantes, conozcan disposiciones para descuento electoral en los recibos de matr\u00edcula correspondientes al per\u00edodo 2017-2 .","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ucaldas.edu.co\/portal\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ucaldas.edu.co\/portal\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\/#article","isPartOf":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\/"},"author":{"name":"ofiprensa","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/person\/a1b482e23449158b4bc319926c074fdf"},"headline":"Estudiantes, conozcan disposiciones para descuento electoral en los recibos de matr\u00edcula correspondientes al per\u00edodo 2017-2","datePublished":"2017-04-26T20:19:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\/"},"wordCount":204,"publisher":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\/#primaryimage"},"thumbnailUrl":"http:\/\/www.ucaldas.edu.co\/intranet2\/wp-content\/uploads\/2015\/11\/MOMENTOS-U-BICENTENAERIO-30-SEP-2014-20-300x200.jpg","keywords":["certificado electoral","descuento","Administraci\u00f3n","matr\u00edcula"],"articleSection":["UCaldas Transparente","Actualidad","Universidad al D\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ucaldas.edu.co\/portal\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\/","url":"https:\/\/www.ucaldas.edu.co\/portal\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\/","name":"Estudiantes, conozcan disposiciones para descuento electoral en los recibos de matr\u00edcula correspondientes al per\u00edodo 2017-2 .","isPartOf":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\/#primaryimage"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\/#primaryimage"},"thumbnailUrl":"http:\/\/www.ucaldas.edu.co\/intranet2\/wp-content\/uploads\/2015\/11\/MOMENTOS-U-BICENTENAERIO-30-SEP-2014-20-300x200.jpg","datePublished":"2017-04-26T20:19:38+00:00","breadcrumb":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ucaldas.edu.co\/portal\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\/#primaryimage","url":"http:\/\/www.ucaldas.edu.co\/intranet2\/wp-content\/uploads\/2015\/11\/MOMENTOS-U-BICENTENAERIO-30-SEP-2014-20-300x200.jpg","contentUrl":"http:\/\/www.ucaldas.edu.co\/intranet2\/wp-content\/uploads\/2015\/11\/MOMENTOS-U-BICENTENAERIO-30-SEP-2014-20-300x200.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ucaldas.edu.co\/portal\/estudiantes-conozcan-disposiciones-para-descuento-electoral-en-los-recibos-de-matricula-correspondientes-al-periodo-2017-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ucaldas.edu.co\/portal\/"},{"@type":"ListItem","position":2,"name":"Estudiantes, conozcan disposiciones para descuento electoral en los recibos de matr\u00edcula correspondientes al per\u00edodo 2017-2"}]},{"@type":"WebSite","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#website","url":"https:\/\/www.ucaldas.edu.co\/portal\/","name":"Universidad de Caldas","description":"","publisher":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization"},"alternateName":"U. de Caldas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ucaldas.edu.co\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization","name":"Universidad de Caldas","alternateName":"U. de Caldas","url":"https:\/\/www.ucaldas.edu.co\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2023\/11\/Logo_horizontal_oscuroU-2023.png","contentUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2023\/11\/Logo_horizontal_oscuroU-2023.png","width":263,"height":101,"caption":"Universidad de Caldas"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/udecaldas","https:\/\/x.com\/udecaldas","https:\/\/www.youtube.com\/universidadcaldas","https:\/\/www.instagram.com\/udecaldas\/"]},{"@type":"Person","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/person\/a1b482e23449158b4bc319926c074fdf","name":"ofiprensa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411","url":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411","contentUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1778102411","caption":"ofiprensa"},"url":"https:\/\/www.ucaldas.edu.co\/portal\/author\/ofiprensa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts\/35203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/comments?post=35203"}],"version-history":[{"count":0,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts\/35203\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/media?parent=35203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/categories?post=35203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/tags?post=35203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}