{"id":17720,"date":"2013-04-19T10:39:46","date_gmt":"2013-04-19T15:39:46","guid":{"rendered":"https:\/\/www.ucaldas.edu.co\/portal\/?p=17720"},"modified":"2013-04-19T10:39:46","modified_gmt":"2013-04-19T15:39:46","slug":"no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco","status":"publish","type":"post","link":"https:\/\/www.ucaldas.edu.co\/portal\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\/","title":{"rendered":"\u201cNo va a haber justicia social sin educaci\u00f3n de calidad para todos\u201d: Juan Carlos Tedesco"},"content":{"rendered":"<p align=\"center\">Exministro de edcaci\u00f3n de Argentina visit\u00f3 la U. de Caldas, en celebraci\u00f3n de sus 70 a\u00f1os<\/p>\n<p align=\"right\">18\/04\/2013<\/p>\n<hr id=\"system-readmore\" \/>\n<p align=\"right\">Redacci\u00f3n: Margarita Laverde Galvis<\/p>\n<p><b>\u00a0<\/b><\/p>\n<table border=\"0\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" style=\"border: 0px\" title=\"Visita\" alt=\"Visita\" src=\"http:\/\/www.ucaldas.edu.co\/images\/tmp\/visitaexministroargentino2013.jpg\" width=\"240\" height=\"150\" border=\"0\" \/><\/p>\n<h6>Foto: Guillermo Sarmiento Estrada\/ Prensa U. de Caldas.<\/h6>\n<\/td>\n<td>Como parte de las <b>actividades<\/b> de la <b>Celebraci\u00f3n<\/b> de los <b>70 a\u00f1os<\/b> de la <b>Universidad de Caldas<\/b>, la <b>Instituci\u00f3n recibi\u00f3<\/b> este jueves 18 de abril del 2013 la <b>visita<\/b> de Juan Carlos Tedesco, <b>exministro de Educaci\u00f3n de Argentina<\/b> y <b>exdirector<\/b> de la <b>Oficina Internacional de Educaci\u00f3n de la Unesco<\/b>, quien <b>orient\u00f3 una conferencia<\/b> en la sala Carlos N\u00e1der.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El <b>Rector de la U. de Caldas, <\/b>Ricardo G\u00f3mez Giraldo, expres\u00f3: \u201ceste es un a\u00f1o de celebraci\u00f3n y con este primer encuentro acad\u00e9mico <b>buscamos reflexionar como Universidad sobre la educaci\u00f3n<\/b>. Precisamente el tema de la conferencia de Tedesco llena mis expectativas y nos alegra tenerlo en nuestra Instituci\u00f3n\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Justicia social<\/b><\/p>\n<p>El invitado disert\u00f3 sobre la <b><i>Educaci\u00f3n y justicia social en Am\u00e9rica Latina<\/i><\/b><i>, <\/i>y expres\u00f3<i>: <\/i>\u201cla b\u00fasqueda de la justicia no tiene fundamentos cient\u00edficos, tiene fundamentos \u00e9ticos y pol\u00edticos. Esta b\u00fasqueda en Am\u00e9rica Latina es leg\u00edtima y genuina. <b>La educaci\u00f3n es condici\u00f3n necesaria de la justicia<\/b>, aunque no es suficiente, pero es claro que <b>sin educaci\u00f3n hoy, el riesgo de quedar excluido es muy grande\u201d.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>\u201c<b>Si queremos construir sociedades m\u00e1s justas, la educaci\u00f3n debe ser uno de los pilares sobre los cuales se pueden apoyar las pol\u00edticas<\/b> en ese terreno. Colombia ha avanzado mucho en cobertura, como la mayor parte de los pa\u00edses de la regi\u00f3n, pero <b>tenemos el desaf\u00edo de la calidad<\/b>, es decir, c\u00f3mo hacer que ese acceso a la educaci\u00f3n sea acceso al conocimiento\u201d, agreg\u00f3 Tedesco.<\/p>\n<p>&nbsp;<\/p>\n<p><b>U. de Caldas, 70 a\u00f1os de historia y calidad<\/b><\/p>\n<p><b>Respecto <\/b>a la celebraci\u00f3n de los 70 a\u00f1os de la U. de Caldas, el invitado coment\u00f3: \u201ccreo que es una celebraci\u00f3n que <b>nos alegra a todos, porque es una universidad p\u00fablica que est\u00e1 mostrando<\/b>, que atendiendo a estudiantes que provienen de los sectores con m\u00e1s bajos ingresos, <b>se puede lograr alto nivel de excelencia<\/b>\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEl <b>compromiso social que tiene la U. de Caldas me parece que es uno de los aspectos m\u00e1s destacables<\/b> y que m\u00e1s se debe celebrar en estos momentos\u201d, enfatiz\u00f3 el invitado.<\/p>\n<p><b>Construcci\u00f3n de la Unidad Formadora de Educadores<\/b><\/p>\n<p>Durante la visita <b>se realiz\u00f3<\/b> adem\u00e1s un <b>encuentro<\/b> con el <b>Director del Departamento de Estudios Educativos <\/b>de la Instituci\u00f3n, para <b>aportar<\/b> en la <b>construcci\u00f3n<\/b> de la <b>Unidad Formadora de Educadores<\/b> y sus componentes esenciales: pedag\u00f3gico, ide\u00e1tico y curricular.<\/p>\n<p>&nbsp;<\/p>\n<p>Henry Portela Guar\u00edn, <b>Director del Departamento de Estudios Educativos y Director de la Maestr\u00eda en Educaci\u00f3n de la U. de Caldas, <\/b>dijo: \u201caprovechamos la visita de Tedesco, quien present\u00f3 una reflexi\u00f3n pedag\u00f3gica sobre el papel de la formaci\u00f3n de educadores en Colombia y en la U. de Caldas.<\/p>\n<p>Se trata de un escenario de contextualizaci\u00f3n y posibilidades para el desarrollo de la educaci\u00f3n\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cDesde all\u00ed, <b>las reflexiones te\u00f3ricas que el profesor nos pueda aportar nos ofrecer\u00e1 elementos, para seguir enriqueciendo nuestra producci\u00f3n acad\u00e9mica<\/b>. En el encuentro participaron los profesores de dicho Departamento de la Instituci\u00f3n, el Decano de la Facultad de Artes y Humanidades, y el Rector de la Instituci\u00f3n\u201d, agreg\u00f3 Portela Guar\u00edn.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.ivoox.com\/exministro-argentino-carlos-tedesco-rueda-prensa-u-audios-mp3_rf_1964653_1.html\" target=\"_blank\">Descargue aqu\u00ed el audio de la rueda de prensa con Juan Carlos Tedesco, exministro de Educaci\u00f3n de Argentina<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.ivoox.com\/preguntas-a-exministro-argentino-carlos-tedesco-u-audios-mp3_rf_1964656_1.html\" target=\"_blank\">Descargue aqu\u00ed el audio de la sesi\u00f3n de preguntas con Juan Carlos Tedesco, exministro de Educaci\u00f3n de Argentina<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.ivoox.com\/exministro-argentino-carlos-tedesco-sobre-70-anos-audios-mp3_rf_1964660_1.html\" target=\"_blank\">Descargue aqu\u00ed el audio de Juan Carlos Tedesco, exministro de Educaci\u00f3n de Argentina, sobre los 70 a\u00f1os de la U. de Caldas<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.504216206306916.1073741932.107054166023124&amp;type=3\" target=\"_blank\">Conozca aqu\u00ed im\u00e1genes de la visita de Juan Carlos Tedesco, exministro de Educaci\u00f3n de Argentina, a la U. de Caldas<\/a><br \/>\n<b>Informes:<\/b>\u00a0Oficina de Prensa de la U. de Caldas, tel\u00e9fono 878 15 00 extensi\u00f3n 12 167.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Exministro de edcaci\u00f3n de Argentina visit\u00f3 la U. de Caldas, en celebraci\u00f3n de sus 70 a\u00f1os 18\/04\/2013 Redacci\u00f3n: Margarita Laverde Galvis \u00a0 Foto: Guillermo Sarmiento Estrada\/ Prensa U. de Caldas. Como parte de las actividades de la Celebraci\u00f3n de los 70 a\u00f1os de la Universidad de Caldas, la Instituci\u00f3n recibi\u00f3 este jueves 18 de abril [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[48,53],"tags":[],"class_list":["post-17720","post","type-post","status-publish","format-standard","hentry","category-actualidad","category-universidad-al-dia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cNo va a haber justicia social sin educaci\u00f3n de calidad para todos\u201d: Juan Carlos Tedesco .<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ucaldas.edu.co\/portal\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\\\/\"},\"author\":{\"name\":\"ofiprensa\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/person\\\/a1b482e23449158b4bc319926c074fdf\"},\"headline\":\"\u201cNo va a haber justicia social sin educaci\u00f3n de calidad para todos\u201d: Juan Carlos Tedesco\",\"datePublished\":\"2013-04-19T15:39:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\\\/\"},\"wordCount\":698,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.ucaldas.edu.co\\\/images\\\/tmp\\\/visitaexministroargentino2013.jpg\",\"articleSection\":[\"Actualidad\",\"Universidad al D\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\\\/\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\\\/\",\"name\":\"\u201cNo va a haber justicia social sin educaci\u00f3n de calidad para todos\u201d: Juan Carlos Tedesco .\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.ucaldas.edu.co\\\/images\\\/tmp\\\/visitaexministroargentino2013.jpg\",\"datePublished\":\"2013-04-19T15:39:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.ucaldas.edu.co\\\/images\\\/tmp\\\/visitaexministroargentino2013.jpg\",\"contentUrl\":\"http:\\\/\\\/www.ucaldas.edu.co\\\/images\\\/tmp\\\/visitaexministroargentino2013.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cNo va a haber justicia social sin educaci\u00f3n de calidad para todos\u201d: Juan Carlos Tedesco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\",\"name\":\"Universidad de Caldas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\"},\"alternateName\":\"U. de Caldas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#organization\",\"name\":\"Universidad de Caldas\",\"alternateName\":\"U. de Caldas\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Logo_horizontal_oscuroU-2023.png\",\"contentUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Logo_horizontal_oscuroU-2023.png\",\"width\":263,\"height\":101,\"caption\":\"Universidad de Caldas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/udecaldas\",\"https:\\\/\\\/x.com\\\/udecaldas\",\"https:\\\/\\\/www.youtube.com\\\/universidadcaldas\",\"https:\\\/\\\/www.instagram.com\\\/udecaldas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/#\\\/schema\\\/person\\\/a1b482e23449158b4bc319926c074fdf\",\"name\":\"ofiprensa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1787779368\",\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1787779368\",\"contentUrl\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/wp-content\\\/litespeed\\\/avatar\\\/09ea5085e600095a7a811142c6944527.jpg?ver=1787779368\",\"caption\":\"ofiprensa\"},\"url\":\"https:\\\/\\\/www.ucaldas.edu.co\\\/portal\\\/author\\\/ofiprensa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cNo va a haber justicia social sin educaci\u00f3n de calidad para todos\u201d: Juan Carlos Tedesco .","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ucaldas.edu.co\/portal\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ucaldas.edu.co\/portal\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\/#article","isPartOf":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\/"},"author":{"name":"ofiprensa","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/person\/a1b482e23449158b4bc319926c074fdf"},"headline":"\u201cNo va a haber justicia social sin educaci\u00f3n de calidad para todos\u201d: Juan Carlos Tedesco","datePublished":"2013-04-19T15:39:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\/"},"wordCount":698,"publisher":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\/#primaryimage"},"thumbnailUrl":"http:\/\/www.ucaldas.edu.co\/images\/tmp\/visitaexministroargentino2013.jpg","articleSection":["Actualidad","Universidad al D\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ucaldas.edu.co\/portal\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\/","url":"https:\/\/www.ucaldas.edu.co\/portal\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\/","name":"\u201cNo va a haber justicia social sin educaci\u00f3n de calidad para todos\u201d: Juan Carlos Tedesco .","isPartOf":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\/#primaryimage"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\/#primaryimage"},"thumbnailUrl":"http:\/\/www.ucaldas.edu.co\/images\/tmp\/visitaexministroargentino2013.jpg","datePublished":"2013-04-19T15:39:46+00:00","breadcrumb":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ucaldas.edu.co\/portal\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\/#primaryimage","url":"http:\/\/www.ucaldas.edu.co\/images\/tmp\/visitaexministroargentino2013.jpg","contentUrl":"http:\/\/www.ucaldas.edu.co\/images\/tmp\/visitaexministroargentino2013.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ucaldas.edu.co\/portal\/no-va-a-haber-justicia-social-sin-educacion-de-calidad-para-todos-juan-carlos-tedesco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ucaldas.edu.co\/portal\/"},{"@type":"ListItem","position":2,"name":"\u201cNo va a haber justicia social sin educaci\u00f3n de calidad para todos\u201d: Juan Carlos Tedesco"}]},{"@type":"WebSite","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#website","url":"https:\/\/www.ucaldas.edu.co\/portal\/","name":"Universidad de Caldas","description":"","publisher":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization"},"alternateName":"U. de Caldas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ucaldas.edu.co\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#organization","name":"Universidad de Caldas","alternateName":"U. de Caldas","url":"https:\/\/www.ucaldas.edu.co\/portal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2023\/11\/Logo_horizontal_oscuroU-2023.png","contentUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/uploads\/2023\/11\/Logo_horizontal_oscuroU-2023.png","width":263,"height":101,"caption":"Universidad de Caldas"},"image":{"@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/udecaldas","https:\/\/x.com\/udecaldas","https:\/\/www.youtube.com\/universidadcaldas","https:\/\/www.instagram.com\/udecaldas\/"]},{"@type":"Person","@id":"https:\/\/www.ucaldas.edu.co\/portal\/#\/schema\/person\/a1b482e23449158b4bc319926c074fdf","name":"ofiprensa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1787779368","url":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1787779368","contentUrl":"https:\/\/www.ucaldas.edu.co\/portal\/wp-content\/litespeed\/avatar\/09ea5085e600095a7a811142c6944527.jpg?ver=1787779368","caption":"ofiprensa"},"url":"https:\/\/www.ucaldas.edu.co\/portal\/author\/ofiprensa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts\/17720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/comments?post=17720"}],"version-history":[{"count":0,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/posts\/17720\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/media?parent=17720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/categories?post=17720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ucaldas.edu.co\/portal\/wp-json\/wp\/v2\/tags?post=17720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}